{"id":10,"date":"2026-03-28T16:28:38","date_gmt":"2026-03-28T16:28:38","guid":{"rendered":"https:\/\/hotelmarcopolo.it\/?page_id=10"},"modified":"2026-06-17T19:43:54","modified_gmt":"2026-06-17T19:43:54","slug":"homepage","status":"publish","type":"page","link":"https:\/\/hotelmarcopolo.it\/de\/","title":{"rendered":"Startseite"},"content":{"rendered":"<div id=\"fws_6a57fd8c3c05b\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-section vc_row-o-full-height vc_row-o-columns-middle vc_row-o-equal-height vc_row-flex parallax_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image\" data-parallax-speed=\"fast\" style=\"background-image: url(https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/Background-Home-1.svg); background-position: center center; background-repeat: no-repeat; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light center\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding el_spacing_0px inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 100px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-split-heading  font_size_95px font_size_phone_65px font_line_height_1-1\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 95px; line-height: 102.6px;\"><h1 style=\" color: #FFFDFC;\">Dove Venedig<\/h1><\/div><div class=\"nectar-split-heading  font_size_95px font_size_phone_65px font_line_height_1-1\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 95px; line-height: 102.6px;\"><h1 style=\" color: #FFFDFC;\">trifft das Meer<\/h1><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 40px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button jumbo regular extra-color-2  regular-button\"  role=\"button\" style=\"color: #817369; \"  href=\"#welcome\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Entdecken Sie Hotel Marco Polo<\/span><\/a>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"welcome\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"10%\" data-bottom-percent=\"10%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color\"  style=\"padding-top: calc(100vw * 0.10); padding-bottom: calc(100vw * 0.10); --row-bg-color: #FFFDFC;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #FFFDFC; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a57fd8c3e1be\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_line_height_1-1\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h1 style=\" color: #817369;\">Eine famili\u00e4re Begr\u00fc\u00dfung, das Meer nur wenige Schritte entfernt und Venedig in greifbarer N\u00e4he.<\/h1><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a57fd8c3ed42\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_line_height_1-4  custom-trigger scroll-timeline\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"scroll-opacity-reveal\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><p style=\" color: #817369;\">Ganz wie Marco Polo, der sich mit seiner Familie aufmachte, um neue Welten zu entdecken, entstand auch unsere Geschichte aus einem Reisegeist. Seit 1998 pflegen wir mit Leidenschaft unser Abenteuer in der Welt der Hotellerie. Heute f\u00fchrt die zweite Generation, Carlotta und Denis, das Hotel Marco Polo 3 Sterne Superior mit Blick in die Zukunft, zwischen Qualit\u00e4t, Nachhaltigkeit und Innovation.<\/p><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57fd8c3f73b\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-full-height vc_row-o-columns-middle vc_row-o-equal-height vc_row-flex vc_row-o-content-top  zindex-set mobile-disable-bg-image-animation nectar-overflow-hidden top_margin_phone_0px\"  style=\"padding-top: 0px; padding-bottom: 0px;  z-index: 100;\"><div class=\"row-bg-wrap\" data-bg-animation=\"fade-in\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" style=\"background-color: #8173691C;\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #8173691C; \"><\/div><\/div><\/div>\n\t\t\t<div class=\"video-color-overlay row-bg-layer\" data-color=\"\"><\/div>\n\t\t\t\n\t\t\t<div class=\"nectar-video-wrap row-bg-layer\" data-bg-alignment=\"\">\n\t\t\t\t<div class=\"nectar-video-inner\">\n\t\t\t\t<video class=\"nectar-video-bg\" width=\"1800\" height=\"700\" preload=\"auto\" loop autoplay muted playsinline><source src=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/06\/hotelmarcopolo_homepagenew.mov\"  type=\"video\/mp4\"><\/video>    \t\t<\/div>\n\t\t\t <\/div>\n\n\t\t\t<div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding column_position_static el_spacing_0px inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"top-bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a57fd8c3fcab\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row  right_padding_13vw left_padding_13vw\"  style=\" z-index: 10;\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57fd8c40339\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"10%\" data-bottom-percent=\"2%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color\"  style=\"padding-top: calc(100vw * 0.10); padding-bottom: calc(100vw * 0.02); --row-bg-color: #FFFDFC;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #FFFDFC; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark center\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a57fd8c407b0\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_line_height_1-1\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h1 style=\" color: #817369;\">Unsere Unterkunftsl\u00f6sungen<\/h1><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57fd8c41649\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark center\">\n\t<div style=\"\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col padding-4-percent inherit_tablet inherit_phone\" data-using-bg=\"true\" data-border-radius=\"10px\" data-bg-cover=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-bg-pos=\"center center\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg\" style=\" background-image: url('https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/44.png'); \"><\/div><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap height_phone_300px\" data-alignment=\"default\"><div style=\"height: 400px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a57fd8c42743\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-bottom\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  center\">\n\t<div style=\"\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column centered-text padding-6-percent el_spacing_0px inherit_tablet inherit_phone backdrop_filter_blur backdrop_blur_1\"  data-using-bg=\"true\" data-border-radius=\"10px\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#A2796B\" data-bg-opacity=\"0.8\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 0.8; background-color: #A2796B;\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-split-heading  font_line_height_1-1\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h1 style=\" color: #FFFDFC;\">Hotel<\/h1><\/div><div class=\"nectar-split-heading  font_line_height_1px\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h1 style=\" color: #FFFDFC;\">Marco Polo<\/h1><\/div><div class=\"nectar-split-heading  font_line_height_1-4\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><p style=\" color: #FFFDFC;\">Unser Hotel im Herzen von Jesolo.<\/p><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-cta  alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit\" data-color=\"default\" data-using-bg=\"false\" data-style=\"arrow-animation\" data-display=\"block\" data-alignment=\"center\" data-text-color=\"custom\" style=\"--nectar-text-color: #FFFDFC; --nectar-button-color: var(--nectar-default); --nectar-icon-gap: 10px; \"><h4 style=\"color: #FFFDFC;\"><span class=\"link_wrap\" ><a  class=\"link_text\" role=\"button\" href=\"https:\/\/hotelmarcopolo.it\/de\/camere-hotel-marco-polo\/\"><span class=\"text\">mehr erkunden<\/span><svg class=\"next-arrow\" aria-hidden=\"true\" width=\"20px\" height=\"25px\" viewbox=\"0 0 50 80\" xml:space=\"preserve\">\n  <polyline stroke=\"#ffffff\" stroke-width=\"9\" fill=\"none\" stroke-linecap=\"round\" stroke-linejoin=\"round\" points=\"0, 0 45, 40 0, 80\"\/>\n  <\/svg>  <span aria-hidden=\"true\" class=\"line\"  style=\"background-color: #FFFDFC;\"><\/span> <\/a><\/span><\/h4><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div style=\"\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col padding-4-percent inherit_tablet inherit_phone\" data-using-bg=\"true\" data-border-radius=\"10px\" data-bg-cover=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-bg-pos=\"center bottom\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg\" style=\" background-image: url('https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/04\/Image-4.jpeg'); \"><\/div><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap height_phone_300px\" data-alignment=\"default\"><div style=\"height: 400px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a57fd8c43f7a\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-bottom\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  center\">\n\t<div style=\"\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column centered-text padding-6-percent el_spacing_0px inherit_tablet inherit_phone backdrop_filter_blur backdrop_blur_1\"  data-using-bg=\"true\" data-border-radius=\"10px\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#E4DFDC\" data-bg-opacity=\"0.7\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 0.7; background-color: #E4DFDC;\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-split-heading  font_line_height_1-1\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h1 style=\" color: #FFFDFC;\">Gold<\/h1><\/div><div class=\"nectar-split-heading  font_line_height_1-1\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h1 style=\" color: #FFFDFC;\">Haus<\/h1><\/div><div class=\"nectar-split-heading  font_line_height_1-4\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><p style=\" color: #FFFDFC;\">Unsere Ferienwohnungen am Meer<\/p><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-cta  alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit\" data-color=\"default\" data-using-bg=\"false\" data-style=\"arrow-animation\" data-display=\"block\" data-alignment=\"center\" data-text-color=\"custom\" style=\"--nectar-text-color: #FFFDFC; --nectar-button-color: var(--nectar-default); --nectar-icon-gap: 10px; \"><h4 style=\"color: #FFFDFC;\"><span class=\"link_wrap\" ><a  class=\"link_text\" role=\"button\" href=\"https:\/\/hotelmarcopolo.it\/de\/appartamenti\/\"><span class=\"text\">mehr erkunden<\/span><svg class=\"next-arrow\" aria-hidden=\"true\" width=\"20px\" height=\"25px\" viewbox=\"0 0 50 80\" xml:space=\"preserve\">\n  <polyline stroke=\"#ffffff\" stroke-width=\"9\" fill=\"none\" stroke-linecap=\"round\" stroke-linejoin=\"round\" points=\"0, 0 45, 40 0, 80\"\/>\n  <\/svg>  <span aria-hidden=\"true\" class=\"line\"  style=\"background-color: #FFFDFC;\"><\/span> <\/a><\/span><\/h4><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57fd8c44d8d\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"10%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color\"  style=\"padding-top: calc(100vw * 0.10); padding-bottom: 0px; --row-bg-color: #FFFDFC;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #FFFDFC; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark center\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a57fd8c4529f\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_line_height_1-1\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h1 style=\" color: #817369;\">Unsere Dienstleistungen, konzipiert f\u00fcr Ihren Aufenthalt<\/h1><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a57fd8c45cea\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_line_height_1-4  custom-trigger scroll-timeline\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"scroll-opacity-reveal\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><p style=\" color: #817369;\">Vom Moment Ihrer Ankunft an ist jedes Detail darauf ausgelegt, Ihnen einen angenehmen Aufenthalt zu bieten, beginnend mit unserem privaten, bequemen und reservierten Parkplatz. Der Tag beginnt mit einem jeden Morgen sorgf\u00e4ltig zubereiteten Fr\u00fchst\u00fcck aus ausgew\u00e4hlten Rohstoffen, das von 7:30 bis 10:30 Uhr serviert wird. Abgerundet wird das Erlebnis durch den privaten Strand mit Liegestuhl und Sonnenschirm, um das Meer in v\u00f6lliger Ruhe zu genie\u00dfen.<\/p><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 50px;\" class=\"divider\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57fd8c46a35\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"services\"  data-column-margin=\"default\" data-midnight=\"dark\" data-bottom-percent=\"6%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  top_margin_2pct nectar-overflow-hidden top_padding_tablet_24pct bottom_padding_tablet_15pct\"  style=\"padding-top: 0px; padding-bottom: calc(100vw * 0.06); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-flickity not-initialized nectar-carousel tb-spacing-0\" data-centered-cells=\"true\" data-pause-on-hover=\"true\" data-touch-icon-color=\"default\" data-control-color=\"default\" data-overflow=\"visible\" data-r-bottom-total=\"\" data-drag-scale=\"\" data-wrap=\"wrap\" data-spacing=\"10px\" data-controls=\"next_prev_arrows_overlaid\" data-pagination-alignment=\"default\" data-adaptive-height=\"\" data-border-radius=\"10px\" data-column-border=\"\" data-column-padding=\"20px\" data-format=\"default\" data-autoplay=\"\" data-autoplay-dur=\"5000\" data-control-style=\"material_pagination\" data-desktop-columns=\"3\" data-small-desktop-columns=\"3\" data-tablet-columns=\"2\" data-phone-columns=\"1\" data-column-color=\"\" style=\"--subtract-from-col-width: 80px;\"><div class=\"flickity-viewport\"> <div class=\"flickity-slider\"><div class=\"cell  nectar-background-gradient-blur flex_layout_desktop_column flex_justify_content_desktop_space-between flex_align_items_desktop_flex-start flex_wrap_desktop_nowrap flex_reverse_desktop_false flex_gap_desktop_10px\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" data-nectar-lazy-bg data-nectar-img-src=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/17.png\"><div class=\"divider-wrap height_phone_250px\" data-alignment=\"default\"><div style=\"height: 350px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a57fd8c493b9\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_layout_desktop_row flex_justify_content_desktop_flex-start flex_align_items_desktop_flex-start flex_wrap_desktop_wrap flex_reverse_desktop_false flex_gap_desktop_8px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-responsive-text nectar-link-underline-effect\" style=\"color: #ffffff;\"><h3>Haustierfreundlich: Das Beste f\u00fcr Ihren vierbeinigen Freund<\/h3>\n<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><div class=\"cell  nectar-background-gradient-blur flex_layout_desktop_column flex_justify_content_desktop_space-between flex_align_items_desktop_flex-start flex_wrap_desktop_nowrap flex_reverse_desktop_false flex_gap_desktop_10px\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" data-nectar-lazy-bg data-nectar-img-src=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/9.png\"><div class=\"nectar_color_layer\" style=\"background:linear-gradient(0deg, rgb(0,0,0) 0%, rgba(0,0,0,0) 36%); opacity:0.2;\" data-h-opacity=\"0.2\"><\/div><div class=\"divider-wrap height_phone_250px\" data-alignment=\"default\"><div style=\"height: 350px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a57fd8c4ab95\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_layout_desktop_row flex_justify_content_desktop_flex-start flex_align_items_desktop_flex-start flex_wrap_desktop_wrap flex_reverse_desktop_false flex_gap_desktop_8px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-responsive-text nectar-link-underline-effect\" style=\"color: #ffffff;\"><h3>Reichhaltiges Fr\u00fchst\u00fcck mit lokalen italienischen Produkten<\/h3>\n<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><div class=\"cell  nectar-background-gradient-blur flex_layout_desktop_column flex_justify_content_desktop_space-between flex_align_items_desktop_flex-start flex_wrap_desktop_nowrap flex_reverse_desktop_false flex_gap_desktop_10px\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" data-nectar-lazy-bg data-nectar-img-src=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/19.png\"><div class=\"nectar_color_layer\" style=\"background:linear-gradient(0deg, rgb(0,0,0) 0%, rgba(0,0,0,0) 37%); opacity:0.2;\" data-h-opacity=\"0.2\"><\/div><div class=\"divider-wrap height_phone_250px\" data-alignment=\"default\"><div style=\"height: 350px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a57fd8c4b671\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_layout_desktop_row flex_justify_content_desktop_flex-start flex_align_items_desktop_flex-start flex_wrap_desktop_wrap flex_reverse_desktop_false flex_gap_desktop_8px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-responsive-text nectar-link-underline-effect\" style=\"color: #ffffff;\"><h3>Privater und garantierter Strandplatz<\/h3>\n<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><div class=\"cell  nectar-background-gradient-blur flex_layout_desktop_column flex_justify_content_desktop_space-between flex_align_items_desktop_flex-start flex_wrap_desktop_nowrap flex_reverse_desktop_false flex_gap_desktop_10px\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" data-nectar-lazy-bg data-nectar-img-src=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/34.png\"><div class=\"nectar_color_layer\" style=\"background:linear-gradient(0deg, rgb(0,0,0) 0%, rgba(0,0,0,0) 36%); opacity:0.2;\" data-h-opacity=\"0.2\"><\/div><div class=\"divider-wrap height_phone_250px\" data-alignment=\"default\"><div style=\"height: 350px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a57fd8c4c9df\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_layout_desktop_row flex_justify_content_desktop_flex-start flex_align_items_desktop_flex-start flex_wrap_desktop_wrap flex_reverse_desktop_false flex_gap_desktop_8px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-responsive-text nectar-link-underline-effect\" style=\"color: #ffffff;\"><h3>Exklusiver und garantierter Fahrraddienst<\/h3>\n<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><div class=\"cell  nectar-background-gradient-blur flex_layout_desktop_column flex_justify_content_desktop_space-between flex_align_items_desktop_flex-start flex_wrap_desktop_nowrap flex_reverse_desktop_false flex_gap_desktop_10px\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" data-nectar-lazy-bg data-nectar-img-src=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/24.png\"><div class=\"divider-wrap height_phone_250px\" data-alignment=\"default\"><div style=\"height: 350px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a57fd8c4df65\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone flex_layout_desktop_row flex_justify_content_desktop_flex-start flex_align_items_desktop_flex-start flex_wrap_desktop_wrap flex_reverse_desktop_false flex_gap_desktop_8px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-responsive-text nectar-link-underline-effect\" style=\"color: #ffffff;\"><h3>Hotel f\u00fcr Ihre Arbeit mit Lounge und WLAN<\/h3>\n<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"testimonials\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"4%\" data-bottom-percent=\"4%\" data-nectar-animated-gradient-settings=\"{&quot;color_1&quot;:&quot;#E4DFDC&quot;,&quot;color_2&quot;:&quot;#FFFDFC&quot;,&quot;speed&quot;:&quot;850&quot;,&quot;blending_mode&quot;:&quot;linear&quot;}\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color\"  style=\"padding-top: calc(100vw * 0.04); padding-bottom: calc(100vw * 0.04); --row-bg-color: #E4DFDC;\"><div class=\"row-bg-wrap has-animated-gradient\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #E4DFDC; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\"margin-top: 30px; margin-bottom: 30px; \" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-carousel-flickity-fixed-content\" data-alignment=\"default\" data-control-color=\"default\"> <div class=\"nectar-carousel-fixed-content\"><\/p>\n<h1>\u00dcBER UNS<\/h1>\n<p><\/div><div class=\"nectar-flickity not-initialized nectar-carousel\" data-centered-cells=\"false\" data-pause-on-hover=\"\" data-touch-icon-color=\"default\" data-control-color=\"default\" data-overflow=\"hidden\" data-r-bottom-total=\"\" data-drag-scale=\"\" data-wrap=\"wrap\" data-spacing=\"default\" data-controls=\"default\" data-pagination-alignment=\"default\" data-adaptive-height=\"\" data-border-radius=\"10px\" data-column-border=\"true\" data-column-padding=\"50px\" data-format=\"fixed_text_content_fullwidth\" data-autoplay=\"true\" data-autoplay-dur=\"7000\" data-control-style=\"material_pagination\" data-desktop-columns=\"3\" data-small-desktop-columns=\"2\" data-tablet-columns=\"1\" data-phone-columns=\"1\" data-column-color=\"#ffffff\"><div class=\"flickity-viewport\"> <div class=\"flickity-slider\"><div class=\"cell  flex_gap_desktop_10px\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" style=\"background-color: #ffffff;\"><blockquote class=\"nectar_single_testimonial\" tabindex=\"0\" data-color=\"\" data-style=\"basic\"><div class=\"inner\"> <p>\u201cZimmerreinigung, Freundlichkeit des Personals, fabelhaftes Fr\u00fchst\u00fcck\u201d <\/p><span class=\"wrap\"><span>Monika<\/span><span class=\"title\">Da Booking.com<\/span><\/span><\/div><\/blockquote><\/div><\/div><\/div><div class=\"cell  flex_gap_desktop_10px\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" style=\"background-color: #ffffff;\"><blockquote class=\"nectar_single_testimonial\" tabindex=\"0\" data-color=\"\" data-style=\"basic\"><div class=\"inner\"> <p>\u201cSaubere und moderne Zimmer. Gem\u00fctliche Unterkunft, reichhaltiges und sehr abwechslungsreiches Fr\u00fchst\u00fcck. Sehr freundliches und hilfsbereites Personal. Sehr zu empfehlen.\u201d <\/p><span class=\"wrap\"><span>Max<\/span><span class=\"title\">Da Booking.com<\/span><\/span><\/div><\/blockquote><\/div><\/div><\/div><div class=\"cell  flex_gap_desktop_10px\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" style=\"background-color: #ffffff;\"><blockquote class=\"nectar_single_testimonial\" tabindex=\"0\" data-color=\"\" data-style=\"basic\"><div class=\"inner\"> <p>\u201cWir haben alles geliebt. Sehr sch\u00f6ne, gepflegte und saubere Anlage. Sehr freundliches Personal. Wundersch\u00f6nes Zimmer. Au\u00dfergew\u00f6hnliches Fr\u00fchst\u00fcck. Sehr gute Lage\u2019 <\/p><span class=\"wrap\"><span>Chiara<\/span><span class=\"title\">Da Booking.com<\/span><\/span><\/div><\/blockquote><\/div><\/div><\/div><div class=\"cell  flex_gap_desktop_10px\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" style=\"background-color: #ffffff;\"><blockquote class=\"nectar_single_testimonial\" tabindex=\"0\" data-color=\"\" data-style=\"basic\"><div class=\"inner\"> <p>\u201cEin sehr sch\u00f6ner Ort mit freundlichem Personal. Zimmer mit allem Komfort, Parkplatz im Innenbereich und vor allem ein ausgezeichnetes Fr\u00fchst\u00fcck, serviert von super freundlichem Personal.<br \/>\nWir werden auf jeden Fall wiederkommen.\u201d <\/p><span class=\"wrap\"><span>Mara und Brio<\/span><span class=\"title\">Da Booking.com<\/span><\/span><\/div><\/blockquote><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57fd8c511ae\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"6%\" data-bottom-percent=\"5%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content has-row-bg-color vc_row-o-equal-height vc_row-flex vc_row-o-content-top  right_padding_60px left_padding_60px top_padding_tablet_15pct right_padding_tablet_25px left_padding_tablet_25px\"  style=\"padding-top: calc(100vw * 0.06); padding-bottom: calc(100vw * 0.05); --row-bg-color: #A2796B;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #A2796B; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding el_spacing_20px inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-responsive-text nectar-link-underline-effect\" data-inherit-heading-family=\"h6\"><p>Die geplanten Angebote<\/p>\n<\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div><div class='nectar-post-grid-wrap text-color-light spacing-15px' data-el-settings='{\"post_type\":\"post\",\"pagination\":\"none\",\"image_size\":\"portfolio-thumb_large\",\"parallax_scrolling\":\"\",\"aspect_ratio_image_size\":\"\",\"category_position\":\"default\",\"category_display\":\"default\",\"display_categories\":\"0\",\"display_excerpt\":\"0\",\"excerpt_length\":\"20\",\"content_next_to_image_excerpt_pos\":\"default\",\"display_date\":\"0\",\"display_estimated_reading_time\":\"0\",\"display_author\":\"0\",\"author_functionality\":\"default\",\"author_position\":\"default\",\"color_overlay\":\"\",\"color_overlay_opacity\":\"\",\"color_overlay_hover_opacity\":\"\",\"card_bg_color\":\"\",\"grid_style\":\"vertical_list\",\"hover_effect\":\"\",\"post_title_overlay\":\"\",\"heading_tag\":\"h1\",\"heading_tag_render\":\"default\",\"enable_gallery_lightbox\":\"0\",\"remove_links\":\"0\",\"category_style\":\"underline\",\"overlay_secondary_project_image\":\"\",\"vertical_list_hover_effect\":\"featured_image_follow\",\"vertical_list_read_more\":\"yes\",\"vertical_list_read_more_style\":\"arrow\",\"read_more_button\":\"0\",\"animation\":\"fade-in-from-bottom\",\"custom_fields\":\"\",\"custom_fields_location\":\"before_post_meta\",\"display_type\":\"grid\",\"text_content_layout\":\"top_left\"}' data-style='vertical_list' data-query='{\"post_type\":\"post\",\"posts_per_page\":\"6\",\"order\":\"DESC\",\"orderby\":\"date\",\"offset\":\"0\",\"cpt_name\":\"post\",\"custom_query_tax\":\"\",\"ignore_sticky_posts\":\"yes\",\"exclude_current_post\":\"\"}' data-load-more-color='black' data-load-more-text='Load More'><div class=\"nectar-post-grid-filters\" data-active-color=\"default\" data-align=\"default\" data-animation=\"fade-in-from-bottom\" data-sortable=\"\"><div><a href=\"#\" class=\"active  all-filter\" data-total-count=\"4\" data-filter=\"-1\">Alle<\/a><a href=\"#\" data-filter=\"offerte\" data-total-count=\"4\">Angebot<\/a><\/div><\/div><div class=\"nectar-post-grid category-position-before-title vert_list_bg_hover_FFFDFC vert_list_text_hover_000000 vert_list_hover_effect_featured_image_follow\" data-indicator=\"\" data-indicator-style=\"default\" data-indicator-text-color=\"#fff\" data-indicator-color=\"#000\" data-indicator-text=\"View\" data-columns=\"1\" data-hover-effect=\"\" data-text-style=\"default\" data-border-radius=\"10px\" data-grid-item-height=\"30vh\" data-grid-spacing=\"15px\" data-text-layout=\"top_left\" data-text-color=\"light\" data-text-hover-color=\"light\" data-shadow-hover=\"\" data-animation=\"fade-in-from-bottom\" data-animation-stagger=\"150\" data-cat-click=\"default\" style=\"--post-grid-border-radius:10px;\" ><div class=\"nectar-post-grid-item\" data-post-id=\"576\" data-has-img=\"true\"> <div class=\"inner\"><div class=\"nectar-post-grid-item-bg-wrap\"><div class=\"nectar-post-grid-item-bg-wrap-inner\"><div class=\"nectar-post-grid-item-bg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"604\" src=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/54-900x604.png\" class=\"nectar-post-grid-item-bg__media wp-post-image\" alt=\"\" srcset=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/54-900x604.png 900w, https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/54-600x403.png 600w, https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/54-400x269.png 400w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/div><div class=\"content\"><a class=\"nectar-post-grid-link\" href=\"https:\/\/hotelmarcopolo.it\/de\/offerta-bimbo-gratis\/\" ><span class=\"screen-reader-text\">Angebot \u201cKind gratis\u201d<\/span><\/a><div class=\"item-main\"><div class=\"post-heading-wrap\"><h1 class=\"post-heading\"><span>Angebot \u201cKind gratis\u201d<\/span><\/h1><\/div><svg class=\"nectar-post-grid-item__arrow\" stroke=\"currentColor\" fill=\"currentColor\" stroke-width=\"0\" viewbox=\"60 58 140 140\" height=\"200px\" width=\"200px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M198,64V168a6,6,0,0,1-12,0V78.48L68.24,196.24a6,6,0,0,1-8.48-8.48L177.52,70H88a6,6,0,0,1,0-12H192A6,6,0,0,1,198,64Z\"><\/path><\/svg><\/div><\/div><\/div><\/div><div class=\"nectar-post-grid-item\" data-post-id=\"572\" data-has-img=\"true\"> <div class=\"inner\"><div class=\"nectar-post-grid-item-bg-wrap\"><div class=\"nectar-post-grid-item-bg-wrap-inner\"><div class=\"nectar-post-grid-item-bg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"604\" src=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/49-900x604.png\" class=\"nectar-post-grid-item-bg__media wp-post-image\" alt=\"\" srcset=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/49-900x604.png 900w, https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/49-600x403.png 600w, https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/49-400x269.png 400w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/div><div class=\"content\"><a class=\"nectar-post-grid-link\" href=\"https:\/\/hotelmarcopolo.it\/de\/offerta-happy-sunday\/\" ><span class=\"screen-reader-text\">Angebot \u201cHappy Sunday\u201d<\/span><\/a><div class=\"item-main\"><div class=\"post-heading-wrap\"><h1 class=\"post-heading\"><span>Angebot \u201cHappy Sunday\u201d<\/span><\/h1><\/div><svg class=\"nectar-post-grid-item__arrow\" stroke=\"currentColor\" fill=\"currentColor\" stroke-width=\"0\" viewbox=\"60 58 140 140\" height=\"200px\" width=\"200px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M198,64V168a6,6,0,0,1-12,0V78.48L68.24,196.24a6,6,0,0,1-8.48-8.48L177.52,70H88a6,6,0,0,1,0-12H192A6,6,0,0,1,198,64Z\"><\/path><\/svg><\/div><\/div><\/div><\/div><div class=\"nectar-post-grid-item\" data-post-id=\"320\" data-has-img=\"true\"> <div class=\"inner\"><div class=\"nectar-post-grid-item-bg-wrap\"><div class=\"nectar-post-grid-item-bg-wrap-inner\"><div class=\"nectar-post-grid-item-bg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"604\" src=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/57-900x604.png\" class=\"nectar-post-grid-item-bg__media wp-post-image\" alt=\"\" srcset=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/57-900x604.png 900w, https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/57-600x403.png 600w, https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/57-400x269.png 400w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/div><div class=\"content\"><a class=\"nectar-post-grid-link\" href=\"https:\/\/hotelmarcopolo.it\/de\/offerta-pet-friendly\/\" ><span class=\"screen-reader-text\">Pet Friendly Angebot<\/span><\/a><div class=\"item-main\"><div class=\"post-heading-wrap\"><h1 class=\"post-heading\"><span>Pet Friendly Angebot<\/span><\/h1><\/div><svg class=\"nectar-post-grid-item__arrow\" stroke=\"currentColor\" fill=\"currentColor\" stroke-width=\"0\" viewbox=\"60 58 140 140\" height=\"200px\" width=\"200px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M198,64V168a6,6,0,0,1-12,0V78.48L68.24,196.24a6,6,0,0,1-8.48-8.48L177.52,70H88a6,6,0,0,1,0-12H192A6,6,0,0,1,198,64Z\"><\/path><\/svg><\/div><\/div><\/div><\/div><div class=\"nectar-post-grid-item\" data-post-id=\"322\" data-has-img=\"true\"> <div class=\"inner\"><div class=\"nectar-post-grid-item-bg-wrap\"><div class=\"nectar-post-grid-item-bg-wrap-inner\"><div class=\"nectar-post-grid-item-bg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"604\" src=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/29-900x604.png\" class=\"nectar-post-grid-item-bg__media wp-post-image\" alt=\"\" srcset=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/29-900x604.png 900w, https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/29-600x403.png 600w, https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/29-400x269.png 400w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/div><div class=\"content\"><a class=\"nectar-post-grid-link\" href=\"https:\/\/hotelmarcopolo.it\/de\/offerta-prenota-con-noi\/\" ><span class=\"screen-reader-text\">Buchen Sie mit uns Angebot<\/span><\/a><div class=\"item-main\"><div class=\"post-heading-wrap\"><h1 class=\"post-heading\"><span>Buchen Sie mit uns Angebot<\/span><\/h1><\/div><svg class=\"nectar-post-grid-item__arrow\" stroke=\"currentColor\" fill=\"currentColor\" stroke-width=\"0\" viewbox=\"60 58 140 140\" height=\"200px\" width=\"200px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M198,64V168a6,6,0,0,1-12,0V78.48L68.24,196.24a6,6,0,0,1-8.48-8.48L177.52,70H88a6,6,0,0,1,0-12H192A6,6,0,0,1,198,64Z\"><\/path><\/svg><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57fd8c57bd4\"  data-column-margin=\"default\" data-midnight=\"light\" data-nectar-animated-gradient-settings=\"{&quot;color_1&quot;:&quot;#E4DFDC&quot;,&quot;color_2&quot;:&quot;#FFFDFC&quot;,&quot;speed&quot;:&quot;1300&quot;,&quot;blending_mode&quot;:&quot;linear&quot;}\"  class=\"wpb_row vc_row-fluid vc_row full-width-section vc_row-o-full-height vc_row-o-columns-middle vc_row-o-equal-height vc_row-flex\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap has-animated-gradient\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image\"  style=\"background-image: url(https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/CHI-SIAMO-BACKGROUND.svg); background-position: center center; background-repeat: no-repeat; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light center\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding el_spacing_0px inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 80px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-split-heading  font_size_95px font_size_phone_65px font_line_height_1-1\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 95px; line-height: 102.6px;\"><h1 style=\" color: #A2796B;\">Wer wir sind<\/h1><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button jumbo regular accent-color  regular-button\"  role=\"button\" style=\"\"  href=\"https:\/\/hotelmarcopolo.it\/de\/chi-siamo\/\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Entdecken Sie unsere Familie<\/span><\/a>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Prenota direttamente con noi e assicurati la miglior offerta\u00a0possibile per il tuo soggiorno a Jesolo! In pi\u00f9, se utilizzi il codice sconto\u00a0Whatsapp, ti riserviamo un\u00a0ulteriore 5% di sconto. Prenota la...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-10","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hotel 3 Stelle Superior a Jesolo vicino al mare | Hotel Marco Polo<\/title>\n<meta name=\"description\" content=\"Soggiorna all\u2019Hotel Marco Polo 3 Stelle Superior a Jesolo, vicino al mare e a Via Bafile. Camere moderne, spiaggia privata e colazione inclusa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotelmarcopolo.it\/de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel 3 Stelle Superior a Jesolo vicino al mare | Hotel Marco Polo\" \/>\n<meta property=\"og:description\" content=\"Soggiorna all\u2019Hotel Marco Polo 3 Stelle Superior a Jesolo, vicino al mare e a Via Bafile. Camere moderne, spiaggia privata e colazione inclusa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotelmarcopolo.it\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Marco Polo Jesolo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HotelMarcoPoloJesolo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-17T19:43:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/Hotel_Marco_Polo_web-1002.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotelmarcopolo.it\\\/\",\"url\":\"https:\\\/\\\/hotelmarcopolo.it\\\/\",\"name\":\"Hotel 3 Stelle Superior a Jesolo vicino al mare | Hotel Marco Polo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotelmarcopolo.it\\\/#website\"},\"datePublished\":\"2026-03-28T16:28:38+00:00\",\"dateModified\":\"2026-06-17T19:43:54+00:00\",\"description\":\"Soggiorna all\u2019Hotel Marco Polo 3 Stelle Superior a Jesolo, vicino al mare e a Via Bafile. Camere moderne, spiaggia privata e colazione inclusa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotelmarcopolo.it\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotelmarcopolo.it\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotelmarcopolo.it\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hotelmarcopolo.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotelmarcopolo.it\\\/#website\",\"url\":\"https:\\\/\\\/hotelmarcopolo.it\\\/\",\"name\":\"Hotel Marco Polo Jesolo\",\"description\":\"Dove Venezia incontra il mare\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotelmarcopolo.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotelmarcopolo.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotelmarcopolo.it\\\/#organization\",\"name\":\"Hotel Marco Polo Jesolo\",\"url\":\"https:\\\/\\\/hotelmarcopolo.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hotelmarcopolo.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotelmarcopolo.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-1.png\",\"contentUrl\":\"https:\\\/\\\/hotelmarcopolo.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-1.png\",\"width\":512,\"height\":512,\"caption\":\"Hotel Marco Polo Jesolo\"},\"image\":{\"@id\":\"https:\\\/\\\/hotelmarcopolo.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HotelMarcoPoloJesolo\",\"https:\\\/\\\/www.instagram.com\\\/marcopolojesolo\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@marcopolo_jesolo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel 3 Stelle Superior a Jesolo vicino al mare | Hotel Marco Polo","description":"Soggiorna all\u2019Hotel Marco Polo 3 Stelle Superior a Jesolo, vicino al mare e a Via Bafile. Camere moderne, spiaggia privata e colazione inclusa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotelmarcopolo.it\/de\/","og_locale":"de_DE","og_type":"article","og_title":"Hotel 3 Stelle Superior a Jesolo vicino al mare | Hotel Marco Polo","og_description":"Soggiorna all\u2019Hotel Marco Polo 3 Stelle Superior a Jesolo, vicino al mare e a Via Bafile. Camere moderne, spiaggia privata e colazione inclusa.","og_url":"https:\/\/hotelmarcopolo.it\/de\/","og_site_name":"Hotel Marco Polo Jesolo","article_publisher":"https:\/\/www.facebook.com\/HotelMarcoPoloJesolo","article_modified_time":"2026-06-17T19:43:54+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/Hotel_Marco_Polo_web-1002.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotelmarcopolo.it\/","url":"https:\/\/hotelmarcopolo.it\/","name":"Hotel 3 Stelle Superior a Jesolo vicino al mare | Hotel Marco Polo","isPartOf":{"@id":"https:\/\/hotelmarcopolo.it\/#website"},"datePublished":"2026-03-28T16:28:38+00:00","dateModified":"2026-06-17T19:43:54+00:00","description":"Soggiorna all\u2019Hotel Marco Polo 3 Stelle Superior a Jesolo, vicino al mare e a Via Bafile. Camere moderne, spiaggia privata e colazione inclusa.","breadcrumb":{"@id":"https:\/\/hotelmarcopolo.it\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotelmarcopolo.it\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotelmarcopolo.it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotelmarcopolo.it\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/hotelmarcopolo.it\/#website","url":"https:\/\/hotelmarcopolo.it\/","name":"Hotel Marco Polo Jesolo","description":"Dove Venezia incontra il mare","publisher":{"@id":"https:\/\/hotelmarcopolo.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotelmarcopolo.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hotelmarcopolo.it\/#organization","name":"Hotel Marco Polo Jesolo","url":"https:\/\/hotelmarcopolo.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hotelmarcopolo.it\/#\/schema\/logo\/image\/","url":"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/cropped-1.png","contentUrl":"https:\/\/hotelmarcopolo.it\/wp-content\/uploads\/2026\/03\/cropped-1.png","width":512,"height":512,"caption":"Hotel Marco Polo Jesolo"},"image":{"@id":"https:\/\/hotelmarcopolo.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HotelMarcoPoloJesolo","https:\/\/www.instagram.com\/marcopolojesolo\/","https:\/\/www.tiktok.com\/@marcopolo_jesolo"]}]}},"_links":{"self":[{"href":"https:\/\/hotelmarcopolo.it\/de\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelmarcopolo.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotelmarcopolo.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotelmarcopolo.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelmarcopolo.it\/de\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":101,"href":"https:\/\/hotelmarcopolo.it\/de\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":847,"href":"https:\/\/hotelmarcopolo.it\/de\/wp-json\/wp\/v2\/pages\/10\/revisions\/847"}],"wp:attachment":[{"href":"https:\/\/hotelmarcopolo.it\/de\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}